{"id":1126348,"date":"2026-05-12T16:19:03","date_gmt":"2026-05-12T14:19:03","guid":{"rendered":"https:\/\/wein-werte.com\/product\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/"},"modified":"2026-05-12T19:52:34","modified_gmt":"2026-05-12T17:52:34","slug":"tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml","status":"publish","type":"product","link":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/","title":{"rendered":"Tement | S\u00fcdsteiermark | Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage | 2021 | 1500ml | bio"},"content":{"rendered":"<p>Produktbeschreibung f\u00fcr Tement Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage 2021 (bio)<\/p>\n<p>Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021 ist ein trockener Wei\u00dfwein hergestellt aus Sauvignon Blanc Trauben in der Region S\u00fcdsteiermark in \u00d6sterreich.<\/p>\n<p>Keywords: <a href=\"https:\/\/wein-werte.com\/de\/shop\/?swoof=1&#038;pa_producer=Tement\">Tement<\/a> <a href=\"https:\/\/wein-werte.com\/de\/shop\/?swoof=1&#038;woof_text=Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage\">Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage<\/a> 2021 bio <a href=\"https:\/\/wein-werte.com\/de\/shop\/?swoof=1&#038;pa_region=S\u00fcdsteiermark\">S\u00fcdsteiermark<\/a> <a href=\"https:\/\/wein-werte.com\/de\/shop\/?swoof=1&#038;pa_country=\u00d6sterreich\">\u00d6sterreich<\/a><\/p>\n<p>Internetseite des Weinguts: <a href=\"https:\/\/www.tement.at\/\" target=\"_blank\">https:\/\/www.tement.at\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"font-size: 14px;\">\n<p>Lieferzeit: 1 bis 2 Arbeitstage (DE), 2 bis 5 Arbeitstage (EU und CH)<\/p>\n<p>Ungef\u00e4hrer Energiegehalt pro 125-ml-Glas: 110 kcal<\/p>\n<\/p><\/div>\n","protected":false},"featured_media":1138526,"template":"","meta":[],"product_brand":[],"product_cat":[19],"product_tag":[],"class_list":{"0":"post-1126348","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-unkategorisiert","7":"pa_alcohol-for-filter-12892","8":"pa_certified-biodynamic-nein-de","9":"pa_certified-organic-ja-de","10":"pa_colour-weiss","11":"pa_country-osterreich","12":"pa_grape-sauvignon-blanc","13":"pa_price-for-filter-10571","14":"pa_producer-tement","15":"pa_region-sudsteiermark","16":"pa_size-ml-6657","17":"pa_sweetness-trocken-de","18":"pa_type-2-still-de","19":"pa_vintage-2021-de","20":"entry","21":"has-media","23":"first","24":"instock","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021, 1500ml<\/title>\n<meta name=\"description\" content=\"Kaufe Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021 (Sauvignon Blanc, trocken aus S\u00fcdsteiermark, \u00d6sterreich) bei Wein Werte, Ihrem nachhaltigen Onlineshop.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021, 1500ml\" \/>\n<meta property=\"og:description\" content=\"Kaufe Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021 (Sauvignon Blanc, trocken aus S\u00fcdsteiermark, \u00d6sterreich) bei Wein Werte, Ihrem nachhaltigen Onlineshop.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Wein Werte\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T17:52:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wein-werte.com\/wp-content\/uploads\/2026\/04\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/\",\"url\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/\",\"name\":\"Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021, 1500ml\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wein-werte.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png\",\"datePublished\":\"2026-05-12T14:19:03+00:00\",\"dateModified\":\"2026-05-12T17:52:34+00:00\",\"description\":\"Kaufe Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021 (Sauvignon Blanc, trocken aus S\u00fcdsteiermark, \u00d6sterreich) bei Wein Werte, Ihrem nachhaltigen Onlineshop.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wein-werte.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png\",\"contentUrl\":\"https:\\\/\\\/wein-werte.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png\",\"width\":350,\"height\":1200,\"caption\":\"Tement Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage 2021 1500ml\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/produkt\\\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tement | S\u00fcdsteiermark | Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage | 2021 | 1500ml | bio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/\",\"name\":\"Wein Werte\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/#organization\",\"name\":\"Vins Fins Thorrold\",\"url\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wein-werte.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Wein_werte_Logo700-1.png\",\"contentUrl\":\"https:\\\/\\\/wein-werte.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Wein_werte_Logo700-1.png\",\"width\":700,\"height\":272,\"caption\":\"Vins Fins Thorrold\"},\"image\":{\"@id\":\"https:\\\/\\\/wein-werte.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021, 1500ml","description":"Kaufe Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021 (Sauvignon Blanc, trocken aus S\u00fcdsteiermark, \u00d6sterreich) bei Wein Werte, Ihrem nachhaltigen Onlineshop.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/","og_locale":"de_DE","og_type":"article","og_title":"Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021, 1500ml","og_description":"Kaufe Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021 (Sauvignon Blanc, trocken aus S\u00fcdsteiermark, \u00d6sterreich) bei Wein Werte, Ihrem nachhaltigen Onlineshop.","og_url":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/","og_site_name":"Wein Werte","article_modified_time":"2026-05-12T17:52:34+00:00","og_image":[{"width":350,"height":1200,"url":"https:\/\/wein-werte.com\/wp-content\/uploads\/2026\/04\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/","url":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/","name":"Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021, 1500ml","isPartOf":{"@id":"https:\/\/wein-werte.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/#primaryimage"},"image":{"@id":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/#primaryimage"},"thumbnailUrl":"https:\/\/wein-werte.com\/wp-content\/uploads\/2026\/04\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png","datePublished":"2026-05-12T14:19:03+00:00","dateModified":"2026-05-12T17:52:34+00:00","description":"Kaufe Tement Ried Zieregg Kapelle Sauvignon blanc Gro\u00dfe STK Lage 2021 (Sauvignon Blanc, trocken aus S\u00fcdsteiermark, \u00d6sterreich) bei Wein Werte, Ihrem nachhaltigen Onlineshop.","breadcrumb":{"@id":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/#primaryimage","url":"https:\/\/wein-werte.com\/wp-content\/uploads\/2026\/04\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png","contentUrl":"https:\/\/wein-werte.com\/wp-content\/uploads\/2026\/04\/Tement-Ried-Zieregg-Kapelle-Sauvignon-blanc-Grosse-STK-Lage-2021-1500ml.png","width":350,"height":1200,"caption":"Tement Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage 2021 1500ml"},{"@type":"BreadcrumbList","@id":"https:\/\/wein-werte.com\/de\/produkt\/tement-ried-zieregg-kapelle-sauvignon-blanc-grosse-stk-lage-2021-1500ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wein-werte.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/wein-werte.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Tement | S\u00fcdsteiermark | Ried Zieregg Kapelle Sauvignon Blanc, Gro\u00dfe STK Lage | 2021 | 1500ml | bio"}]},{"@type":"WebSite","@id":"https:\/\/wein-werte.com\/de\/#website","url":"https:\/\/wein-werte.com\/de\/","name":"Wein Werte","description":"","publisher":{"@id":"https:\/\/wein-werte.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wein-werte.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wein-werte.com\/de\/#organization","name":"Vins Fins Thorrold","url":"https:\/\/wein-werte.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wein-werte.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/wein-werte.com\/wp-content\/uploads\/2023\/07\/Wein_werte_Logo700-1.png","contentUrl":"https:\/\/wein-werte.com\/wp-content\/uploads\/2023\/07\/Wein_werte_Logo700-1.png","width":700,"height":272,"caption":"Vins Fins Thorrold"},"image":{"@id":"https:\/\/wein-werte.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/product\/1126348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/media\/1138526"}],"wp:attachment":[{"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/media?parent=1126348"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/product_brand?post=1126348"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/product_cat?post=1126348"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wein-werte.com\/de\/wp-json\/wp\/v2\/product_tag?post=1126348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}